{"id":8755,"date":"2025-05-07T10:15:04","date_gmt":"2025-05-07T08:15:04","guid":{"rendered":"https:\/\/mallorcaconventionbureau.com\/miembros\/alsa"},"modified":"2025-10-29T12:56:59","modified_gmt":"2025-10-29T10:56:59","slug":"alsa","status":"publish","type":"miembros","link":"https:\/\/mallorcaconventionbureau.com\/en\/miembros\/alsa","title":{"rendered":"ALSA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8755\" class=\"elementor elementor-8755 elementor-3264\" data-elementor-post-type=\"miembros\">\n\t\t\t\t<div class=\"elementor-element elementor-element-283ec01b e-flex e-con-boxed e-con e-parent\" data-id=\"283ec01b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-567e5b48 elementor-invisible elementor-widget elementor-widget-qi_addons_for_elementor_image_slider\" data-id=\"567e5b48\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"qi_addons_for_elementor_image_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-slider qodef-qi-fslightbox-popup qodef-popup-gallery qodef-col-num--2 qodef-qi-grid qodef-qi-swiper-container qodef-navigation--inside qodef-pagination--outside qodef-navigation--hover-move\" data-options=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;slidesPerView&quot;:&quot;2&quot;,&quot;spaceBetween&quot;:20,&quot;spaceBetweenTablet&quot;:20,&quot;spaceBetweenMobile&quot;:20,&quot;effect&quot;:&quot;&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;centeredSlides&quot;:false,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;&quot;,&quot;outsideNavigation&quot;:&quot;no&quot;,&quot;outsidePagination&quot;:&quot;yes&quot;,&quot;unique&quot;:249,&quot;partialValue&quot;:0.2,&quot;disablePartialValue&quot;:&quot;&quot;,&quot;parallax&quot;:&quot;no&quot;}\">\n\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/autobuses_alsa_madrid_fotografia_profesional_miguel_rosan0064.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/autobuses_alsa_madrid_fotografia_profesional_miguel_rosan0064.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/autobuses_alsa_madrid_fotografia_profesional_miguel_rosan0064.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/autobuses_alsa_madrid_fotografia_profesional_miguel_rosan0064-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/autobuses_alsa_madrid_fotografia_profesional_miguel_rosan0064-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/ALSA_BUS_CONFORT.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/ALSA_BUS_CONFORT.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/ALSA_BUS_CONFORT.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/ALSA_BUS_CONFORT-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/ALSA_BUS_CONFORT-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-1.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-1-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-1-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-3.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-3.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-3-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/1-3-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/210407_ALSA_ConstantinDelCastillo_Card_05_0138.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/210407_ALSA_ConstantinDelCastillo_Card_05_0138.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/210407_ALSA_ConstantinDelCastillo_Card_05_0138.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/210407_ALSA_ConstantinDelCastillo_Card_05_0138-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/210407_ALSA_ConstantinDelCastillo_Card_05_0138-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa_9.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa_9.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa_9.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa_9-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa_9-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa-13.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa-13.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa-13.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa-13-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Alsa-13-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Imagen1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Imagen1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Imagen1.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Imagen1-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/Imagen1-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5769.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5769.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5769.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5769-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5769-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5688.jpg\" data-type=\"image\" data-fslightbox=\"gallery-249\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"450\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5688.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5688.jpg 850w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5688-300x159.jpg 300w, https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/2025\/05\/O0A5688-768x407.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\t<\/div>\n\t\t<div class=\"swiper-button-prev\"><svg class=\"qodef-swiper-arrow-left\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewBox=\"0 0 34.2 32.3\" xml:space=\"preserve\" style=\"stroke-width: 2;\"><line x1=\"0.5\" y1=\"16\" x2=\"33.5\" y2=\"16\"\/><line x1=\"0.3\" y1=\"16.5\" x2=\"16.2\" y2=\"0.7\"\/><line x1=\"0\" y1=\"15.4\" x2=\"16.2\" y2=\"31.6\"\/><\/svg><\/div>\n\t<div class=\"swiper-button-next\"><svg class=\"qodef-swiper-arrow-right\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewBox=\"0 0 34.2 32.3\" xml:space=\"preserve\" style=\"stroke-width: 2;\"><line x1=\"0\" y1=\"16\" x2=\"33\" y2=\"16\"\/><line x1=\"17.3\" y1=\"0.7\" x2=\"33.2\" y2=\"16.5\"\/><line x1=\"17.3\" y1=\"31.6\" x2=\"33.5\" y2=\"15.4\"\/><\/svg><\/div>\n<\/div>\n\t<div class=\"swiper-pagination qodef-swiper-pagination-outside swiper-pagination-249\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44f111b1 e-con-full e-flex e-con e-child\" data-id=\"44f111b1\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b2ca40e e-con-full e-flex e-con e-child\" data-id=\"b2ca40e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a8c5d51 elementor-widget elementor-widget-image\" data-id=\"6a8c5d51\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/mallorcaconventionbureau.com\/wp-content\/uploads\/elementor\/thumbs\/Diseno-sin-titulo-24-r5gd9lbkiyb79e4ulzzrtwc9e82nkhfenwv87htuwo.png\" title=\"Dise\u00f1o sin t\u00edtulo\" alt=\"Dise\u00f1o sin t\u00edtulo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f2e8713 e-flex e-con-boxed e-con e-parent\" data-id=\"4f2e8713\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5ad2131b e-con-full e-flex e-con e-child\" data-id=\"5ad2131b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e81b1f2 e-con-full e-flex e-con e-child\" data-id=\"e81b1f2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35ecba39 elementor-invisible elementor-widget elementor-widget-qi_addons_for_elementor_animated_text\" data-id=\"35ecba39\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"qi_addons_for_elementor_animated_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-animated-text qodef--animated-by-word qodef-qi--has-appear qodef--appear-from-bottom\" >\n\t\t<h1 class=\"qodef-m-title\">\n\t\t<span class=\"qodef-e-word\">ALSA<\/span>\t<\/h1>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c2f9f9 e-flex e-con-boxed e-con e-parent\" data-id=\"6c2f9f9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-95216f6 e-con-full e-flex e-con e-child\" data-id=\"95216f6\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-902f64d e-con-full e-flex e-con e-child\" data-id=\"902f64d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b05f47 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9b05f47\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The mobility company Alsa specializes in coach rental for all types of tourist and charter services: congresses, excursions, transfers, incentive trips\u2026 and has extensive experience in managing transportation logistics for large events.<\/p><p>Alsa offers a wide fleet distinguished by its safety, comfort, and spaciousness, with personalized services adapted to any situation, equipped with the latest technology and the highest standards of quality, safety, and sustainability\u2014backed by the guarantee of highly qualified professionals. <\/p><p>Alsa Advantages:<\/p><p><br>\u2022 Wide fleet of vehicles to meet the mobility needs of every client and event:<br> \u2022 Chauffeured cars for private transfers<br> \u2022 Premium vans with 7 and 9 seats<br> \u2022 Minibuses with 10 to 19 seats<br> \u2022 Premium coaches with 19 to 59 seats<br>\u2022 Flexibility and responsiveness to changes in the event program<br>\u2022 Bilingual drivers<br>\u2022 Wi-Fi availability<br>\u2022 Preventive safety measures against Covid<br>\u2022 Environmentally committed mobility<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80ba705 e-con-full e-flex e-con e-child\" data-id=\"80ba705\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b06f615 e-con-full e-flex e-con e-child\" data-id=\"b06f615\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fd8d179 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"fd8d179\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70ef847 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"70ef847\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Category<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-852abc1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"852abc1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/mallorcaconventionbureau.com\/en\/transportation-companies\" rel=\"tag\">Transportation Companies<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de79825 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"de79825\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7cb9bc4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7cb9bc4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Address<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-975eae6 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"975eae6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.google.es\/maps\/place\/ALSA\/@39.5388077,2.733269,17z\/data=!3m1!4b1!4m6!3m5!1s0x12979559e4278cfd:0xcf17e79b48d0c4c!8m2!3d39.5388036!4d2.7358439!16s%2Fg%2F11p_8p5_p6?entry=ttu&#038;g_ep=EgoyMDI1MDUwMy4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">Carrer del Camp Franc, 23, Llevant, 07199 Palma, Illes Balears<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e8d2a00 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"e8d2a00\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e42dc73 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e42dc73\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">RRSS<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f58f52 elementor-widget__width-inherit elementor-widget elementor-widget-elementskit-social-media\" data-id=\"9f58f52\" data-element_type=\"widget\" data-widget_type=\"elementskit-social-media.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t\t <ul class=\"ekit_social_media\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-2c332fc\">\n\t\t\t\t\t    <a href=\"https:\/\/x.com\/Alsa_autobuses\" aria-label=\"X\" class=\"twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-55d14c8\">\n\t\t\t\t\t    <a href=\"https:\/\/www.youtube.com\/c\/alsaes\" aria-label=\"youtube\" class=\"v\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-youtube-v\"><\/i>\t\t\t\t\t\t\t\t\t\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-7254661\">\n\t\t\t\t\t    <a href=\"https:\/\/www.facebook.com\/alsaautobuses\/\" aria-label=\"Facebook\" class=\"facebook\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>\t\t\t\t\t\t\t\t\t\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-651ed09\">\n\t\t\t\t\t    <a href=\"https:\/\/www.instagram.com\/alsa\/\" aria-label=\"Instagram\" class=\"1\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-instagram-1\"><\/i>\t\t\t\t\t\t\t\t\t\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-7cf1132\">\n\t\t\t\t\t    <a href=\"https:\/\/www.linkedin.com\/company\/alsa\/\" aria-label=\"Linkedin\" class=\"in\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-63006b3\">\n\t\t\t\t\t    <a href=\"https:\/\/www.tiktok.com\/@alsa\" aria-label=\"Tik tok\" class=\"tiktok\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-tiktok\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448,209.91a210.06,210.06,0,0,1-122.77-39.25V349.38A162.55,162.55,0,1,1,185,188.31V278.2a74.62,74.62,0,1,0,52.23,71.18V0l88,0a121.18,121.18,0,0,0,1.86,22.17h0A122.18,122.18,0,0,0,381,102.39a121.43,121.43,0,0,0,67,20.14Z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-938b75b\">\n\t\t\t\t\t    <a href=\"https:\/\/www.alsa.es\/\" aria-label=\"Website\" class=\"earth\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-earth\"><\/i>\t\t\t\t\t\t\t\t\t\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f7a108 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3f7a108\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5363191 elementor-align-right elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-button\" data-id=\"5363191\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6ODA1LCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ff290e e-flex e-con-boxed e-con e-parent\" data-id=\"4ff290e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-75dc8ed1 e-con-full e-flex e-con e-child\" data-id=\"75dc8ed1\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Welcome to your dream Mediterranean getaway. Nestled in a large, private natural setting, at Four Seasons Resort Mallorca in Formentor, relax on our golden sandy beach or in the shade of our iconic pine trees.<\/p>\n","protected":false},"featured_media":8363,"template":"elementor_header_footer","categories":[47],"class_list":["post-8755","miembros","type-miembros","status-publish","has-post-thumbnail","hentry","category-transportation-companies"],"_links":{"self":[{"href":"https:\/\/mallorcaconventionbureau.com\/en\/wp-json\/wp\/v2\/miembros\/8755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mallorcaconventionbureau.com\/en\/wp-json\/wp\/v2\/miembros"}],"about":[{"href":"https:\/\/mallorcaconventionbureau.com\/en\/wp-json\/wp\/v2\/types\/miembros"}],"version-history":[{"count":2,"href":"https:\/\/mallorcaconventionbureau.com\/en\/wp-json\/wp\/v2\/miembros\/8755\/revisions"}],"predecessor-version":[{"id":9568,"href":"https:\/\/mallorcaconventionbureau.com\/en\/wp-json\/wp\/v2\/miembros\/8755\/revisions\/9568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mallorcaconventionbureau.com\/en\/wp-json\/wp\/v2\/media\/8363"}],"wp:attachment":[{"href":"https:\/\/mallorcaconventionbureau.com\/en\/wp-json\/wp\/v2\/media?parent=8755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mallorcaconventionbureau.com\/en\/wp-json\/wp\/v2\/categories?post=8755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}